{"id":116436,"date":"2016-03-03T15:27:27","date_gmt":"2016-03-03T15:27:27","guid":{"rendered":"https:\/\/www.free-word.org\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/"},"modified":"2016-03-03T15:27:27","modified_gmt":"2016-03-03T15:27:27","slug":"lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles","status":"publish","type":"post","link":"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/","title":{"rendered":"lettre in English"},"content":{"rendered":"\n\n<div class=\"fw-definition-fren\">\n  <div class=\"fw-menubar\"><\/div>\n  <div>\n    <div class=\"fw-paragraphe\">\n      <div class=\"fw-entree\">lettre<\/div>\n      <div class=\"fw-voix\"><\/div>\n      <div class=\"fw-txt fw-signifie\">means in English<\/div>\n      <div class=\"fw-definition\">letter<\/div>\n      <div class=\"fw-point\">.<\/div>\n    <\/div>\n\n  <\/div>\n  <p class=\"aligncenter morep\"> <a href=\"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/#more-116436\" class=\"more-link\">(more&hellip;)<\/a><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Translate lettre in English<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"footnotes":""},"categories":[24],"tags":[25,22,8],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"en","enabled_languages":["fr","el","en","es"],"languages":{"fr":{"title":true,"content":true,"excerpt":true},"el":{"title":true,"content":false,"excerpt":true},"en":{"title":true,"content":false,"excerpt":true},"es":{"title":true,"content":false,"excerpt":true}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>lettre in English - Free Dictionary<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-\u03c3\u03c4\u03b1-\u03b1\u03b3\u03b3\u03bb\u03b9\u03ba\u03ac-lettre-in-english-lettre-en-ingles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"lettre in English - Free Dictionary\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-\u03c3\u03c4\u03b1-\u03b1\u03b3\u03b3\u03bb\u03b9\u03ba\u03ac-lettre-in-english-lettre-en-ingles\/\" \/>\n<meta property=\"og:site_name\" content=\"Free Dictionary\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-03T15:27:27+00:00\" \/>\n<meta name=\"author\" content=\"Randy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Randy\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/\"},\"author\":{\"name\":\"Randy\",\"@id\":\"https:\/\/www.free-word.org\/#\/schema\/person\/86ab40bf362d6db33a7cd0a2dd0b05af\"},\"headline\":\"lettre in English\",\"datePublished\":\"2016-03-03T15:27:27+00:00\",\"dateModified\":\"2016-03-03T15:27:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/\"},\"wordCount\":29,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.free-word.org\/#organization\"},\"keywords\":[\"Dictionnaire fran\u00e7ais-anglais\",\"Traduire en anglais\",\"Traduire en fran\u00e7ais\"],\"articleSection\":[\"Dictionnaire fran\u00e7ais-anglais\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/\",\"url\":\"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/\",\"name\":\"lettre in English - Free Dictionary\",\"isPartOf\":{\"@id\":\"https:\/\/www.free-word.org\/#website\"},\"datePublished\":\"2016-03-03T15:27:27+00:00\",\"dateModified\":\"2016-03-03T15:27:27+00:00\",\"description\":\"Translate lettre in English - Free bilingual dictionaries \/ Translation\",\"breadcrumb\":{\"@id\":\"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dictionaries\",\"item\":\"https:\/\/www.free-word.org\/en\/d\/dictionnaires\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dictionnaire fran\u00e7ais-anglais\",\"item\":\"https:\/\/www.free-word.org\/d\/dictionnaires\/dictionnaire-francais-anglais\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"lettre in English\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.free-word.org\/#website\",\"url\":\"https:\/\/www.free-word.org\/\",\"name\":\"Free Dictionary\",\"description\":\"Free bilingual dictionaries \/ Translation\",\"publisher\":{\"@id\":\"https:\/\/www.free-word.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.free-word.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.free-word.org\/#organization\",\"name\":\"Free Word\",\"url\":\"https:\/\/www.free-word.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.free-word.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.free-word.org\/wp-content\/uploads\/sites\/2\/2016\/02\/freeword-icon-1.png\",\"contentUrl\":\"https:\/\/www.free-word.org\/wp-content\/uploads\/sites\/2\/2016\/02\/freeword-icon-1.png\",\"width\":512,\"height\":512,\"caption\":\"Free Word\"},\"image\":{\"@id\":\"https:\/\/www.free-word.org\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.free-word.org\/#\/schema\/person\/86ab40bf362d6db33a7cd0a2dd0b05af\",\"name\":\"Randy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.free-word.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9acd759245246334a3be9ab09b905d55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9acd759245246334a3be9ab09b905d55?s=96&d=mm&r=g\",\"caption\":\"Randy\"},\"url\":\"https:\/\/www.free-word.org\/en\/author\/jules\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"lettre in English - Free Dictionary","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-\u03c3\u03c4\u03b1-\u03b1\u03b3\u03b3\u03bb\u03b9\u03ba\u03ac-lettre-in-english-lettre-en-ingles\/","og_locale":"en_US","og_type":"article","og_title":"lettre in English - Free Dictionary","og_url":"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-\u03c3\u03c4\u03b1-\u03b1\u03b3\u03b3\u03bb\u03b9\u03ba\u03ac-lettre-in-english-lettre-en-ingles\/","og_site_name":"Free Dictionary","article_published_time":"2016-03-03T15:27:27+00:00","author":"Randy","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Randy"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/#article","isPartOf":{"@id":"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/"},"author":{"name":"Randy","@id":"https:\/\/www.free-word.org\/#\/schema\/person\/86ab40bf362d6db33a7cd0a2dd0b05af"},"headline":"lettre in English","datePublished":"2016-03-03T15:27:27+00:00","dateModified":"2016-03-03T15:27:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/"},"wordCount":29,"commentCount":0,"publisher":{"@id":"https:\/\/www.free-word.org\/#organization"},"keywords":["Dictionnaire fran\u00e7ais-anglais","Traduire en anglais","Traduire en fran\u00e7ais"],"articleSection":["Dictionnaire fran\u00e7ais-anglais"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/","url":"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/","name":"lettre in English - Free Dictionary","isPartOf":{"@id":"https:\/\/www.free-word.org\/#website"},"datePublished":"2016-03-03T15:27:27+00:00","dateModified":"2016-03-03T15:27:27+00:00","description":"Translate lettre in English - Free bilingual dictionaries \/ Translation","breadcrumb":{"@id":"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.free-word.org\/en\/lettre-en-anglais-lettre-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-lettre-in-english-lettre-en-ingles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dictionaries","item":"https:\/\/www.free-word.org\/en\/d\/dictionnaires\/"},{"@type":"ListItem","position":2,"name":"Dictionnaire fran\u00e7ais-anglais","item":"https:\/\/www.free-word.org\/d\/dictionnaires\/dictionnaire-francais-anglais\/"},{"@type":"ListItem","position":3,"name":"lettre in English"}]},{"@type":"WebSite","@id":"https:\/\/www.free-word.org\/#website","url":"https:\/\/www.free-word.org\/","name":"Free Dictionary","description":"Free bilingual dictionaries \/ Translation","publisher":{"@id":"https:\/\/www.free-word.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.free-word.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.free-word.org\/#organization","name":"Free Word","url":"https:\/\/www.free-word.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.free-word.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.free-word.org\/wp-content\/uploads\/sites\/2\/2016\/02\/freeword-icon-1.png","contentUrl":"https:\/\/www.free-word.org\/wp-content\/uploads\/sites\/2\/2016\/02\/freeword-icon-1.png","width":512,"height":512,"caption":"Free Word"},"image":{"@id":"https:\/\/www.free-word.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.free-word.org\/#\/schema\/person\/86ab40bf362d6db33a7cd0a2dd0b05af","name":"Randy","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.free-word.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9acd759245246334a3be9ab09b905d55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9acd759245246334a3be9ab09b905d55?s=96&d=mm&r=g","caption":"Randy"},"url":"https:\/\/www.free-word.org\/en\/author\/jules\/"}]}},"_links":{"self":[{"href":"https:\/\/www.free-word.org\/en\/wp-json\/wp\/v2\/posts\/116436"}],"collection":[{"href":"https:\/\/www.free-word.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.free-word.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.free-word.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.free-word.org\/en\/wp-json\/wp\/v2\/comments?post=116436"}],"version-history":[{"count":0,"href":"https:\/\/www.free-word.org\/en\/wp-json\/wp\/v2\/posts\/116436\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.free-word.org\/en\/wp-json\/wp\/v2\/media?parent=116436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.free-word.org\/en\/wp-json\/wp\/v2\/categories?post=116436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.free-word.org\/en\/wp-json\/wp\/v2\/tags?post=116436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}