{"id":83143,"date":"2016-02-28T14:35:07","date_gmt":"2016-02-28T14:35:07","guid":{"rendered":"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/"},"modified":"2016-02-28T14:35:07","modified_gmt":"2016-02-28T14:35:07","slug":"luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles","status":"publish","type":"post","link":"https:\/\/www.free-word.org\/es\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/","title":{"rendered":"luktsalt en ingl\u00e9s"},"content":{"rendered":"\n\n<div class=\"fw-definition-sven\">\n  <div class=\"fw-menubar\"><\/div>\n  <div>\n    <div class=\"fw-paragraphe\">\n      <div class=\"fw-entree\">luktsalt<\/div>\n      <div class=\"fw-voix\"><\/div>\n      <div class=\"fw-txt fw-signifie\">significa en ingl\u00e9s<\/div>\n      <div class=\"fw-definition\">salvolatile<\/div>\n      <div class=\"fw-point\">.<\/div>\n    <\/div>\n\n  <\/div>\n  <p class=\"aligncenter morep\"> <a href=\"https:\/\/www.free-word.org\/es\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/#more-83143\" class=\"more-link\">(m\u00e1s&hellip;)<\/a><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Traducir luktsalt en ingl\u00e9s<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"footnotes":""},"categories":[20],"tags":[21,22,23],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"es","enabled_languages":["fr","el","en","es"],"languages":{"fr":{"title":true,"content":true,"excerpt":true},"el":{"title":true,"content":false,"excerpt":true},"en":{"title":true,"content":false,"excerpt":true},"es":{"title":true,"content":false,"excerpt":true}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>luktsalt en ingl\u00e9s - Diccionario gratuito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-\u03c3\u03c4\u03b1-\u03b1\u03b3\u03b3\u03bb\u03b9\u03ba\u03ac-luktsalt-in-english-luktsalt-en-ingles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"luktsalt en ingl\u00e9s - Diccionario gratuito\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-\u03c3\u03c4\u03b1-\u03b1\u03b3\u03b3\u03bb\u03b9\u03ba\u03ac-luktsalt-in-english-luktsalt-en-ingles\/\" \/>\n<meta property=\"og:site_name\" content=\"Diccionario gratuito\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-28T14:35:07+00:00\" \/>\n<meta name=\"author\" content=\"Randy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Randy\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/\"},\"author\":{\"name\":\"Randy\",\"@id\":\"https:\/\/www.free-word.org\/#\/schema\/person\/86ab40bf362d6db33a7cd0a2dd0b05af\"},\"headline\":\"luktsalt en ingl\u00e9s\",\"datePublished\":\"2016-02-28T14:35:07+00:00\",\"dateModified\":\"2016-02-28T14:35:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/\"},\"wordCount\":29,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.free-word.org\/#organization\"},\"keywords\":[\"Dictionnaire su\u00e9dois-anglais\",\"Traduire en anglais\",\"Traduire en su\u00e9dois\"],\"articleSection\":[\"Dictionnaire su\u00e9dois-anglais\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/\",\"url\":\"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/\",\"name\":\"luktsalt en ingl\u00e9s - Diccionario gratuito\",\"isPartOf\":{\"@id\":\"https:\/\/www.free-word.org\/#website\"},\"datePublished\":\"2016-02-28T14:35:07+00:00\",\"dateModified\":\"2016-02-28T14:35:07+00:00\",\"description\":\"Traducir luktsalt en ingl\u00e9s - Diccionarios gratis \/ Traducci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dictionaries\",\"item\":\"https:\/\/www.free-word.org\/en\/d\/dictionnaires\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dictionnaire su\u00e9dois-anglais\",\"item\":\"https:\/\/www.free-word.org\/en\/d\/dictionnaires\/dictionnaire-suedois-anglais\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"luktsalt en anglais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.free-word.org\/#website\",\"url\":\"https:\/\/www.free-word.org\/\",\"name\":\"Diccionario gratuito\",\"description\":\"Diccionarios gratis \/ Traducci\u00f3n\",\"publisher\":{\"@id\":\"https:\/\/www.free-word.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.free-word.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.free-word.org\/#organization\",\"name\":\"Free Word\",\"url\":\"https:\/\/www.free-word.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.free-word.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.free-word.org\/wp-content\/uploads\/sites\/2\/2016\/02\/freeword-icon-1.png\",\"contentUrl\":\"https:\/\/www.free-word.org\/wp-content\/uploads\/sites\/2\/2016\/02\/freeword-icon-1.png\",\"width\":512,\"height\":512,\"caption\":\"Free Word\"},\"image\":{\"@id\":\"https:\/\/www.free-word.org\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.free-word.org\/#\/schema\/person\/86ab40bf362d6db33a7cd0a2dd0b05af\",\"name\":\"Randy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.free-word.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9acd759245246334a3be9ab09b905d55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9acd759245246334a3be9ab09b905d55?s=96&d=mm&r=g\",\"caption\":\"Randy\"},\"url\":\"https:\/\/www.free-word.org\/es\/author\/jules\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"luktsalt en ingl\u00e9s - Diccionario gratuito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-\u03c3\u03c4\u03b1-\u03b1\u03b3\u03b3\u03bb\u03b9\u03ba\u03ac-luktsalt-in-english-luktsalt-en-ingles\/","og_locale":"es_ES","og_type":"article","og_title":"luktsalt en ingl\u00e9s - Diccionario gratuito","og_url":"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-\u03c3\u03c4\u03b1-\u03b1\u03b3\u03b3\u03bb\u03b9\u03ba\u03ac-luktsalt-in-english-luktsalt-en-ingles\/","og_site_name":"Diccionario gratuito","article_published_time":"2016-02-28T14:35:07+00:00","author":"Randy","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Randy"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/#article","isPartOf":{"@id":"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/"},"author":{"name":"Randy","@id":"https:\/\/www.free-word.org\/#\/schema\/person\/86ab40bf362d6db33a7cd0a2dd0b05af"},"headline":"luktsalt en ingl\u00e9s","datePublished":"2016-02-28T14:35:07+00:00","dateModified":"2016-02-28T14:35:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/"},"wordCount":29,"commentCount":0,"publisher":{"@id":"https:\/\/www.free-word.org\/#organization"},"keywords":["Dictionnaire su\u00e9dois-anglais","Traduire en anglais","Traduire en su\u00e9dois"],"articleSection":["Dictionnaire su\u00e9dois-anglais"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/","url":"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/","name":"luktsalt en ingl\u00e9s - Diccionario gratuito","isPartOf":{"@id":"https:\/\/www.free-word.org\/#website"},"datePublished":"2016-02-28T14:35:07+00:00","dateModified":"2016-02-28T14:35:07+00:00","description":"Traducir luktsalt en ingl\u00e9s - Diccionarios gratis \/ Traducci\u00f3n","breadcrumb":{"@id":"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.free-word.org\/luktsalt-en-anglais-luktsalt-%cf%83%cf%84%ce%b1-%ce%b1%ce%b3%ce%b3%ce%bb%ce%b9%ce%ba%ce%ac-luktsalt-in-english-luktsalt-en-ingles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dictionaries","item":"https:\/\/www.free-word.org\/en\/d\/dictionnaires\/"},{"@type":"ListItem","position":2,"name":"Dictionnaire su\u00e9dois-anglais","item":"https:\/\/www.free-word.org\/en\/d\/dictionnaires\/dictionnaire-suedois-anglais\/"},{"@type":"ListItem","position":3,"name":"luktsalt en anglais"}]},{"@type":"WebSite","@id":"https:\/\/www.free-word.org\/#website","url":"https:\/\/www.free-word.org\/","name":"Diccionario gratuito","description":"Diccionarios gratis \/ Traducci\u00f3n","publisher":{"@id":"https:\/\/www.free-word.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.free-word.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.free-word.org\/#organization","name":"Free Word","url":"https:\/\/www.free-word.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.free-word.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.free-word.org\/wp-content\/uploads\/sites\/2\/2016\/02\/freeword-icon-1.png","contentUrl":"https:\/\/www.free-word.org\/wp-content\/uploads\/sites\/2\/2016\/02\/freeword-icon-1.png","width":512,"height":512,"caption":"Free Word"},"image":{"@id":"https:\/\/www.free-word.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.free-word.org\/#\/schema\/person\/86ab40bf362d6db33a7cd0a2dd0b05af","name":"Randy","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.free-word.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9acd759245246334a3be9ab09b905d55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9acd759245246334a3be9ab09b905d55?s=96&d=mm&r=g","caption":"Randy"},"url":"https:\/\/www.free-word.org\/es\/author\/jules\/"}]}},"_links":{"self":[{"href":"https:\/\/www.free-word.org\/es\/wp-json\/wp\/v2\/posts\/83143"}],"collection":[{"href":"https:\/\/www.free-word.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.free-word.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.free-word.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.free-word.org\/es\/wp-json\/wp\/v2\/comments?post=83143"}],"version-history":[{"count":0,"href":"https:\/\/www.free-word.org\/es\/wp-json\/wp\/v2\/posts\/83143\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.free-word.org\/es\/wp-json\/wp\/v2\/media?parent=83143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.free-word.org\/es\/wp-json\/wp\/v2\/categories?post=83143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.free-word.org\/es\/wp-json\/wp\/v2\/tags?post=83143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}